{"id":668,"date":"2024-09-11T14:21:25","date_gmt":"2024-09-11T12:21:25","guid":{"rendered":"https:\/\/axtra-energy.be\/?page_id=668"},"modified":"2025-01-16T18:19:15","modified_gmt":"2025-01-16T17:19:15","slug":"energie-audit-voor-uw-woning","status":"publish","type":"page","link":"https:\/\/axtra-energy.be\/nl\/energie-audit-voor-uw-woning\/","title":{"rendered":"Energie-audit voor uw woning"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":495,"parent":0,"menu_order":7,"comment_status":"closed","ping_status":"closed","template":"template-image.blade.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-668","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Energieaudit woning | Energie-effici\u00ebntie met Axtra Energy<\/title>\n<meta name=\"description\" content=\"Optimaliseer de energie-effici\u00ebntie van uw huis met Axtra Energy: volledige audit, advies en verkrijgen van premies.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/axtra-energy.be\/nl\/energie-audit-voor-uw-woning\/\" \/>\n<meta property=\"og:locale\" content=\"nl_BE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Energieaudit woning | Energie-effici\u00ebntie met Axtra Energy\" \/>\n<meta property=\"og:description\" content=\"Optimaliseer de energie-effici\u00ebntie van uw huis met Axtra Energy: volledige audit, advies en verkrijgen van premies.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/axtra-energy.be\/nl\/energie-audit-voor-uw-woning\/\" \/>\n<meta property=\"og:site_name\" content=\"Axtra Energy\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/axtraenergy\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-16T17:19:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/axtra-energy.be\/wp-content\/uploads\/2024\/09\/AdobeStock_939589154-1024x683.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/axtra-energy.be\\\/nl\\\/energie-audit-voor-uw-woning\\\/\",\"url\":\"https:\\\/\\\/axtra-energy.be\\\/nl\\\/energie-audit-voor-uw-woning\\\/\",\"name\":\"Energieaudit woning | Energie-effici\u00ebntie met Axtra Energy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/axtra-energy.be\\\/nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/axtra-energy.be\\\/nl\\\/energie-audit-voor-uw-woning\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/axtra-energy.be\\\/nl\\\/energie-audit-voor-uw-woning\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/axtra-energy.be\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/AdobeStock_939589154-e1728976942542.jpeg\",\"datePublished\":\"2024-09-11T12:21:25+00:00\",\"dateModified\":\"2025-01-16T17:19:15+00:00\",\"description\":\"Optimaliseer de energie-effici\u00ebntie van uw huis met Axtra Energy: volledige audit, advies en verkrijgen van premies.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/axtra-energy.be\\\/nl\\\/energie-audit-voor-uw-woning\\\/#breadcrumb\"},\"inLanguage\":\"nl-BE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/axtra-energy.be\\\/nl\\\/energie-audit-voor-uw-woning\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-BE\",\"@id\":\"https:\\\/\\\/axtra-energy.be\\\/nl\\\/energie-audit-voor-uw-woning\\\/#primaryimage\",\"url\":\"https:\\\/\\\/axtra-energy.be\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/AdobeStock_939589154-e1728976942542.jpeg\",\"contentUrl\":\"https:\\\/\\\/axtra-energy.be\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/AdobeStock_939589154-e1728976942542.jpeg\",\"width\":5376,\"height\":3584,\"caption\":\"A visual representation of a home energy audit, with an expert evaluating areas for potential energy savings\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/axtra-energy.be\\\/nl\\\/energie-audit-voor-uw-woning\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/axtra-energy.be\\\/nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Energie-audit voor uw woning\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/axtra-energy.be\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/axtra-energy.be\\\/nl\\\/\",\"name\":\"Axtra Energy\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/axtra-energy.be\\\/nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/axtra-energy.be\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-BE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/axtra-energy.be\\\/nl\\\/#organization\",\"name\":\"Axtra Energy\",\"url\":\"https:\\\/\\\/axtra-energy.be\\\/nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-BE\",\"@id\":\"https:\\\/\\\/axtra-energy.be\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/axtra-energy.be\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/AdobeStock_761214081.jpeg\",\"contentUrl\":\"https:\\\/\\\/axtra-energy.be\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/AdobeStock_761214081.jpeg\",\"width\":3064,\"height\":2043,\"caption\":\"Axtra Energy\"},\"image\":{\"@id\":\"https:\\\/\\\/axtra-energy.be\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/axtraenergy\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Energieaudit woning | Energie-effici\u00ebntie met Axtra Energy","description":"Optimaliseer de energie-effici\u00ebntie van uw huis met Axtra Energy: volledige audit, advies en verkrijgen van premies.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/axtra-energy.be\/nl\/energie-audit-voor-uw-woning\/","og_locale":"nl_BE","og_type":"article","og_title":"Energieaudit woning | Energie-effici\u00ebntie met Axtra Energy","og_description":"Optimaliseer de energie-effici\u00ebntie van uw huis met Axtra Energy: volledige audit, advies en verkrijgen van premies.","og_url":"https:\/\/axtra-energy.be\/nl\/energie-audit-voor-uw-woning\/","og_site_name":"Axtra Energy","article_publisher":"https:\/\/www.facebook.com\/axtraenergy","article_modified_time":"2025-01-16T17:19:15+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/axtra-energy.be\/wp-content\/uploads\/2024\/09\/AdobeStock_939589154-1024x683.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Geschatte leestijd":"6 minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/axtra-energy.be\/nl\/energie-audit-voor-uw-woning\/","url":"https:\/\/axtra-energy.be\/nl\/energie-audit-voor-uw-woning\/","name":"Energieaudit woning | Energie-effici\u00ebntie met Axtra Energy","isPartOf":{"@id":"https:\/\/axtra-energy.be\/nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/axtra-energy.be\/nl\/energie-audit-voor-uw-woning\/#primaryimage"},"image":{"@id":"https:\/\/axtra-energy.be\/nl\/energie-audit-voor-uw-woning\/#primaryimage"},"thumbnailUrl":"https:\/\/axtra-energy.be\/wp-content\/uploads\/2024\/09\/AdobeStock_939589154-e1728976942542.jpeg","datePublished":"2024-09-11T12:21:25+00:00","dateModified":"2025-01-16T17:19:15+00:00","description":"Optimaliseer de energie-effici\u00ebntie van uw huis met Axtra Energy: volledige audit, advies en verkrijgen van premies.","breadcrumb":{"@id":"https:\/\/axtra-energy.be\/nl\/energie-audit-voor-uw-woning\/#breadcrumb"},"inLanguage":"nl-BE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/axtra-energy.be\/nl\/energie-audit-voor-uw-woning\/"]}]},{"@type":"ImageObject","inLanguage":"nl-BE","@id":"https:\/\/axtra-energy.be\/nl\/energie-audit-voor-uw-woning\/#primaryimage","url":"https:\/\/axtra-energy.be\/wp-content\/uploads\/2024\/09\/AdobeStock_939589154-e1728976942542.jpeg","contentUrl":"https:\/\/axtra-energy.be\/wp-content\/uploads\/2024\/09\/AdobeStock_939589154-e1728976942542.jpeg","width":5376,"height":3584,"caption":"A visual representation of a home energy audit, with an expert evaluating areas for potential energy savings"},{"@type":"BreadcrumbList","@id":"https:\/\/axtra-energy.be\/nl\/energie-audit-voor-uw-woning\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/axtra-energy.be\/nl\/"},{"@type":"ListItem","position":2,"name":"Energie-audit voor uw woning"}]},{"@type":"WebSite","@id":"https:\/\/axtra-energy.be\/nl\/#website","url":"https:\/\/axtra-energy.be\/nl\/","name":"Axtra Energy","description":"","publisher":{"@id":"https:\/\/axtra-energy.be\/nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/axtra-energy.be\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-BE"},{"@type":"Organization","@id":"https:\/\/axtra-energy.be\/nl\/#organization","name":"Axtra Energy","url":"https:\/\/axtra-energy.be\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-BE","@id":"https:\/\/axtra-energy.be\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/axtra-energy.be\/wp-content\/uploads\/2024\/09\/AdobeStock_761214081.jpeg","contentUrl":"https:\/\/axtra-energy.be\/wp-content\/uploads\/2024\/09\/AdobeStock_761214081.jpeg","width":3064,"height":2043,"caption":"Axtra Energy"},"image":{"@id":"https:\/\/axtra-energy.be\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/axtraenergy"]}]}},"_links":{"self":[{"href":"https:\/\/axtra-energy.be\/nl\/wp-json\/wp\/v2\/pages\/668","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/axtra-energy.be\/nl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/axtra-energy.be\/nl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/axtra-energy.be\/nl\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/axtra-energy.be\/nl\/wp-json\/wp\/v2\/comments?post=668"}],"version-history":[{"count":0,"href":"https:\/\/axtra-energy.be\/nl\/wp-json\/wp\/v2\/pages\/668\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/axtra-energy.be\/nl\/wp-json\/wp\/v2\/media\/495"}],"wp:attachment":[{"href":"https:\/\/axtra-energy.be\/nl\/wp-json\/wp\/v2\/media?parent=668"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}